{"id":3924,"date":"2023-12-11T09:17:02","date_gmt":"2023-12-11T08:17:02","guid":{"rendered":"http:\/\/s1073265861.online.de\/?p=3924"},"modified":"2024-12-16T14:39:52","modified_gmt":"2024-12-16T13:39:52","slug":"neue-sonderausstellung-in-molsdorf-gestrandete-arche-ulf-rickmann","status":"archive","type":"post","link":"http:\/\/schatzkammer-thueringen.de\/en\/neue-sonderausstellung-in-molsdorf-gestrandete-arche-ulf-rickmann\/","title":{"rendered":"Neue Sonderausstellung in Molsdorf: \u201eGESTRANDETE ARCHE.\u201c \u2013 Ulf Rickmann"},"content":{"rendered":"<p><em>Bis 05.05.2024<\/em><\/p>\n<p>Die Natur in ihrer scheinbaren Realit\u00e4t geben Rickmann Inspiration in der k\u00fcnstlerischen Auseinandersetzung in Malerei und Grafik. Die ins Bild gebrachten Darstellungen von scheinbar existierenden Kleinstlebewesen wie z.B. Insekten, im Schwarm oder einzeln, geben dem Bild einen r\u00e4tselhaften wie mystischen Ausdruck. Oft auch ins Skurrile gesteigert, findet Rickmanns Kunst Anerkennung auf nationalen wie internationalen Ausstellungen. Eine Kooperation mit der Galerie Thoms (M\u00fchlhausen).<\/p>\n<p>Ulf H. Rickmann wurde 1959 in Leipzig geboren und absolvierte von 1982 bis 1985 in Erfurt bei E. A. Zimmermann Kurse in den Techniken Lithografie und Radierung. Seit 1989 arbeitet er freiberuflich als Maler, Grafiker und Fotograf. Seine Metiers sind die Landschaft und die Naturstudie. Er l\u00e4sst sich vom Objekt oder vor Ort inspirieren, er zitiert Landschaften aus der Epoche der Romantik und Abbildungen aus naturkundlichen B\u00fcchern des 18. Jahrhunderts, wobei der Einsatz der grafischen Mittel die formal autonomen Beziehungen (Kontraste, Harmonien) betont und die Sujets in unsere Gegenwart transportiert.<\/p>\n<p>Bildunterschrift: Ulf Rickmann, Metamorphose IX, 2020<\/p>","protected":false},"excerpt":{"rendered":"<p>Bis 05.05.2024 Die Natur in ihrer scheinbaren Realit\u00e4t geben Rickmann Inspiration in der k\u00fcnstlerischen Auseinandersetzung in Malerei und Grafik. Die ins Bild gebrachten Darstellungen von scheinbar existierenden Kleinstlebewesen wie z.B. Insekten, im Schwarm oder einzeln, geben dem Bild einen r\u00e4tselhaften wie mystischen Ausdruck. Oft auch ins Skurrile gesteigert, findet Rickmanns Kunst Anerkennung auf nationalen wie [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3926,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"post_folder":[],"class_list":["post-3924","post","type-post","status-archive","format-standard","has-post-thumbnail","hentry","category-aktuelles"],"_links":{"self":[{"href":"http:\/\/schatzkammer-thueringen.de\/en\/wp-json\/wp\/v2\/posts\/3924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/schatzkammer-thueringen.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/schatzkammer-thueringen.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/schatzkammer-thueringen.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/schatzkammer-thueringen.de\/en\/wp-json\/wp\/v2\/comments?post=3924"}],"version-history":[{"count":0,"href":"http:\/\/schatzkammer-thueringen.de\/en\/wp-json\/wp\/v2\/posts\/3924\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/schatzkammer-thueringen.de\/en\/wp-json\/wp\/v2\/media\/3926"}],"wp:attachment":[{"href":"http:\/\/schatzkammer-thueringen.de\/en\/wp-json\/wp\/v2\/media?parent=3924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/schatzkammer-thueringen.de\/en\/wp-json\/wp\/v2\/categories?post=3924"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/schatzkammer-thueringen.de\/en\/wp-json\/wp\/v2\/tags?post=3924"},{"taxonomy":"post_folder","embeddable":true,"href":"http:\/\/schatzkammer-thueringen.de\/en\/wp-json\/wp\/v2\/post_folder?post=3924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}